{"id":41612,"date":"2026-07-10T10:16:49","date_gmt":"2026-07-10T10:16:49","guid":{"rendered":"https:\/\/greenagritec.com\/"},"modified":"2026-08-08T08:56:14","modified_gmt":"2026-08-08T08:56:14","slug":"aspirapolvere-da-cantiere-metabo-asa-20l-per-solidi-e-liquidi-20l-pc-1200w-602085000","status":"publish","type":"product","link":"https:\/\/greenagritec.com\/it\/prodotto-2\/aspirapolvere-da-cantiere-metabo-asa-20l-per-solidi-e-liquidi-20l-pc-1200w-602085000\/","title":{"rendered":"Metabo ASA 20 L PC Aspirapolvere per solidi e liquidi \u2013 20 L \u2013 1200 W \u2013 602085000"},"content":{"rendered":"<p class=\"isSelectedEnd\">IL <strong>Metabo ASA 20 L PC<\/strong> est un aspirateur professionnel eau et poussi\u00e8re con\u00e7u pour une utilisation r\u00e9guli\u00e8re sur les chantiers, dans les ateliers, les garages et les environnements de travail exigeants.<\/p>\n<p class=\"isSelectedEnd\">Gr\u00e2ce \u00e0 sa puissance maximale de <strong>1200 W<\/strong>, son d\u00e9bit d\u2019air pouvant atteindre <strong>4 200 l\/min<\/strong> et sa d\u00e9pression maximale de <strong>225 hPa<\/strong>, il assure une aspiration efficace des poussi\u00e8res, copeaux, d\u00e9bris et liquides.<\/p>\n<p class=\"isSelectedEnd\">Certifi\u00e9 selon la <strong>classe de poussi\u00e8re L<\/strong>, il est adapt\u00e9 \u00e0 l\u2019aspiration des poussi\u00e8res pr\u00e9sentant une faible valeur limite d\u2019exposition professionnelle. Son homologation industrielle permet une utilisation professionnelle pour les applications d\u2019aspiration \u00e0 sec et humide.<\/p>\n<p class=\"isSelectedEnd\">Il sistema <strong>PressClean<\/strong> permet de nettoyer le filtre rapidement et efficacement pendant les pauses de travail. Une simple activation du syst\u00e8me g\u00e9n\u00e8re un puissant flux d\u2019air invers\u00e9 afin de r\u00e9duire l\u2019encrassement du filtre et de maintenir les performances d\u2019aspiration.<\/p>\n<p class=\"isSelectedEnd\">L\u2019aspirateur est \u00e9galement \u00e9quip\u00e9 d\u2019une <strong>prise int\u00e9gr\u00e9e avec fonction marche\/arr\u00eat automatique<\/strong>. Lorsqu\u2019un outil \u00e9lectroportatif raccord\u00e9 est mis en marche, l\u2019aspirateur d\u00e9marre automatiquement. Apr\u00e8s l\u2019arr\u00eat de l\u2019outil, la fonction de temporisation maintient bri\u00e8vement l\u2019aspiration afin de vider compl\u00e8tement le tuyau.<\/p>\n<p class=\"isSelectedEnd\">Son \u00e9quipement antistatique de base contribue \u00e0 limiter l\u2019accumulation de charges \u00e9lectrostatiques pendant l\u2019utilisation.<\/p>\n<p class=\"isSelectedEnd\">Compact et pratique, le Metabo ASA 20 L PC dispose de supports int\u00e9gr\u00e9s permettant de ranger facilement le c\u00e2ble d\u2019alimentation, le flexible d\u2019aspiration et les accessoires.<\/p>\n<h2>Caratteristiche principali:<\/h2>\n<p class=\"isSelectedEnd\">\u2713 Aspirateur professionnel pour poussi\u00e8res et liquides<br \/>\n\u2713 Puissant moteur de 1 200 W<br \/>\n\u2713 Cuve robuste d\u2019une capacit\u00e9 de 20 litres<br \/>\n\u2713 Certification selon la classe de poussi\u00e8re L<br \/>\n\u2713 D\u00e9bit d\u2019air maximal de 4 200 l\/min<br \/>\n\u2713 D\u00e9pression maximale de 225 hPa<br \/>\n\u2713 Syst\u00e8me de nettoyage manuel du filtre PressClean<br \/>\n\u2713 Prise int\u00e9gr\u00e9e pour outils \u00e9lectroportatifs<br \/>\n\u2713 D\u00e9marrage et arr\u00eat automatiques avec l\u2019outil raccord\u00e9<br \/>\n\u2713 Fonction de temporisation pour vider compl\u00e8tement le flexible<br \/>\n\u2713 \u00c9quipement antistatique de base<br \/>\n\u2713 Flexible d\u2019aspiration professionnel de 3,2 m\u00e8tres<br \/>\n\u2713 Supports int\u00e9gr\u00e9s pour le c\u00e2ble, le flexible et les accessoires<br \/>\n\u2713 Convient aux chantiers, ateliers, garages et travaux de r\u00e9novation<\/p>\n<h2><\/h2>\n<table>\n<tbody>\n<tr>\n<th>\u00a0 Specifiche tecniche<\/th>\n<th>Dettagli del prodotto<\/th>\n<\/tr>\n<tr>\n<td>Marca<\/td>\n<td>Metabo<\/td>\n<\/tr>\n<tr>\n<td>Modello<\/td>\n<td>ASA 20 L PC<\/td>\n<\/tr>\n<tr>\n<td>Riferimento del produttore<\/td>\n<td>602085000<\/td>\n<\/tr>\n<tr>\n<td>Code EAN \/ GTIN<\/td>\n<td>4061792230712<\/td>\n<\/tr>\n<tr>\n<td>Type d\u2019aspirateur<\/td>\n<td>Aspirapolvere per liquidi e solidi<\/td>\n<\/tr>\n<tr>\n<td>Puissance absorb\u00e9e maximale<\/td>\n<td>1200 W<\/td>\n<\/tr>\n<tr>\n<td>Capacit\u00e0 del serbatoio<\/td>\n<td>20 L<\/td>\n<\/tr>\n<tr>\n<td>Classe di polvere<\/td>\n<td>Classe L<\/td>\n<\/tr>\n<tr>\n<td>Flusso d&#039;aria massimo<\/td>\n<td>4 200 l\/min<\/td>\n<\/tr>\n<tr>\n<td>Massima depressione<\/td>\n<td>225 hPa \/ mbar<\/td>\n<\/tr>\n<tr>\n<td>Surface du filtre<\/td>\n<td>3 500 cm\u00b2<\/td>\n<\/tr>\n<tr>\n<td>Diametro del tubo flessibile<\/td>\n<td>32 mm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza del tubo flessibile<\/td>\n<td>3,2 m<\/td>\n<\/tr>\n<tr>\n<td>Longueur du c\u00e2ble \u00e9lectrique<\/td>\n<td>5,5 m<\/td>\n<\/tr>\n<tr>\n<td>Peso<\/td>\n<td>10 kg<\/td>\n<\/tr>\n<tr>\n<td>Pulizia del filtro<\/td>\n<td>Syst\u00e8me manuel PressClean<\/td>\n<\/tr>\n<tr>\n<td>Aspirazione di liquido<\/td>\n<td>S\u00cc<\/td>\n<\/tr>\n<tr>\n<td>Prise pour outil \u00e9lectroportatif<\/td>\n<td>S\u00cc<\/td>\n<\/tr>\n<tr>\n<td>Marche\/arr\u00eat automatique<\/td>\n<td>S\u00cc<\/td>\n<\/tr>\n<tr>\n<td>Fonction de temporisation<\/td>\n<td>S\u00cc<\/td>\n<\/tr>\n<tr>\n<td>\u00c9quipement antistatique<\/td>\n<td>Oui, \u00e9quipement de base<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>\u00c9quipements et accessoires inclus:<\/h2>\n<p class=\"isSelectedEnd\">Le Metabo ASA 20 L PC est livr\u00e9 avec :<\/p>\n<ul data-spread=\"false\">\n<li>1 flexible d\u2019aspiration de \u00d8 32 mm et de 3,2 m de longueur<\/li>\n<li>1 manchon de raccordement Quick \u00d8 28\/35 mm<\/li>\n<li>1 adaptateur de poign\u00e9e Quick Professional<\/li>\n<li>3 tubes d\u2019aspiration en plastique<\/li>\n<li>1 sac filtrant en non-tiss\u00e9<\/li>\n<li>1 suceur pour fentes<\/li>\n<li>1 buse de sol de 300 mm<\/li>\n<li>1 buse d\u2019aspiration de 120 mm<\/li>\n<\/ul>\n<h2>Usi consigliati:<\/h2>\n<p class=\"isSelectedEnd\">Cet aspirateur convient notamment pour :<\/p>\n<ul data-spread=\"false\">\n<li>Les chantiers de construction<\/li>\n<li>Les travaux de r\u00e9novation<\/li>\n<li>Les ateliers professionnels<\/li>\n<li>Les garages<\/li>\n<li>Les travaux de menuiserie<\/li>\n<li>L\u2019aspiration des copeaux et poussi\u00e8res<\/li>\n<li>Le raccordement aux outils \u00e9lectroportatifs<\/li>\n<li>L\u2019aspiration de poussi\u00e8res lors du pon\u00e7age<\/li>\n<li>Le nettoyage des sols professionnels<\/li>\n<li>L\u2019aspiration de salet\u00e9s s\u00e8ches<\/li>\n<li>L\u2019aspiration de liquides<\/li>\n<\/ul>\n<h2>Avantages du syst\u00e8me PressClean<\/h2>\n<p class=\"isSelectedEnd\">Le syst\u00e8me PressClean facilite le nettoyage du filtre pendant les pauses de travail. Il permet de r\u00e9duire l\u2019accumulation de poussi\u00e8re dans le filtre et contribue \u00e0 maintenir une puissance d\u2019aspiration r\u00e9guli\u00e8re.<\/p>\n<p class=\"isSelectedEnd\">Ce syst\u00e8me est particuli\u00e8rement utile lors des travaux produisant une quantit\u00e9 importante de poussi\u00e8res, notamment le pon\u00e7age, le per\u00e7age, le sciage et les travaux de r\u00e9novation.<\/p>\n<h2>Presa per elettroutensile integrata<\/h2>\n<p class=\"isSelectedEnd\">La prise int\u00e9gr\u00e9e permet de raccorder directement un outil \u00e9lectroportatif compatible.<\/p>\n<p class=\"isSelectedEnd\">Lorsque l\u2019outil d\u00e9marre, l\u2019aspirateur se met automatiquement en marche. Apr\u00e8s l\u2019arr\u00eat de l\u2019outil, l\u2019aspirateur continue \u00e0 fonctionner bri\u00e8vement afin d\u2019\u00e9vacuer les poussi\u00e8res encore pr\u00e9sentes dans le flexible.<\/p>\n<p class=\"isSelectedEnd\">Cette fonction permet de maintenir un espace de travail plus propre tout en limitant la dispersion des poussi\u00e8res.<\/p>\n<h2>Contenuto della consegna<\/h2>\n<p class=\"isSelectedEnd\">1 \u00d7 Aspirateur de chantier Metabo ASA 20 L PC<br \/>\n1 \u00d7 Flexible d\u2019aspiration \u00d8 32 mm \u2013 longueur 3,2 m<br \/>\n1 \u00d7 Manchon de raccordement Quick \u00d8 28\/35 mm<br \/>\n1 \u00d7 Adaptateur de poign\u00e9e Quick Professional<br \/>\n3 \u00d7 Tubes d\u2019aspiration en plastique<br \/>\n1 \u00d7 Sac filtrant en non-tiss\u00e9<br \/>\n1 x Bocchetta per fessure<br \/>\n1 \u00d7 Buse de sol de 300 mm<br \/>\n1 \u00d7 Buse d\u2019aspiration de 120 mm<\/p>\n<h2>Informazioni aggiuntive<\/h2>\n<p class=\"isSelectedEnd\"><strong>Utilizzo:<\/strong> professionnel et particulier<br \/>\n<strong>Tipo di utilizzo:<\/strong> aspiration \u00e0 sec et humide<br \/>\n<strong>Classe de poussi\u00e8re :<\/strong> L<br \/>\n<strong>Garantie :<\/strong> selon les conditions du fabricant Metabo<br \/>\n<strong>Disponibilit\u00e9 :<\/strong> 10 unit\u00e9s en stock<\/p>\n<p>Les caract\u00e9ristiques, accessoires et \u00e9quipements peuvent \u00eatre modifi\u00e9s par le fabricant sans pr\u00e9avis.<\/p>","protected":false},"excerpt":{"rendered":"<p>Consegna rapida in Europa (3-7 giorni)<br \/>\nPagamento sicuro<\/p>","protected":false},"featured_media":41836,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1074],"product_cat":[917,961,960,333],"product_tag":[],"class_list":["post-41612","product","type-product","status-publish","has-post-thumbnail","product_brand-metabo","product_cat-aspirateurs-industriels","product_cat-aspirateurs-industriels-2","product_cat-equipements-de-nettoyage","product_cat-ga-detailling","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product\/41612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/comments?post=41612"}],"version-history":[{"count":0,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product\/41612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/media\/41836"}],"wp:attachment":[{"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/media?parent=41612"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product_brand?post=41612"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product_cat?post=41612"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/greenagritec.com\/it\/wp-json\/wp\/v2\/product_tag?post=41612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}